{"id":1905,"date":"2019-07-17T17:34:12","date_gmt":"2019-07-17T20:34:12","guid":{"rendered":"http:\/\/folhadopirajucara.com.br\/?p=1905"},"modified":"2019-07-17T17:38:16","modified_gmt":"2019-07-17T20:38:16","slug":"sera-que-o-deputado-estadual-e-o-candidato-de-ney-santos-a-prefeito-em-taboao-da-serra","status":"publish","type":"post","link":"https:\/\/folhadopirajucara.com.br\/index.php\/2019\/07\/17\/sera-que-o-deputado-estadual-e-o-candidato-de-ney-santos-a-prefeito-em-taboao-da-serra\/","title":{"rendered":"Ser\u00e1 que o Deputado Estadual \u00e9 o candidato de Ney Santos \u00e1 prefeito em Tabo\u00e3o da Serra?"},"content":{"rendered":"<p>Nesta semana, no Canal Folha do Piraju\u00e7ara, eu apresento alguns fatos interessantes e, para n\u00e3o dizer, tamb\u00e9m preocupantes. Trata-se de uma situa\u00e7\u00e3o envolvendo Emendas Parlamentares do deputado Jos\u00e9 Apr\u00edgio ao munic\u00edpio de Embu das Artes. Essas emendas seriam uma reinvindica\u00e7\u00e3o do jovem e promissor pol\u00edtico embuense, vereador Andr\u00e9 Maestri. Por\u00e9m, o prefeito de Embu das Artes Ney Santos, teria proibido o deputado de encaminhar as tais emendas, atendendo pedido de um vereador de oposi\u00e7\u00e3o. O deputado em absurda obedi\u00eancia ao prefeito, mandou avisar ao vereador que as emendas estavam suspensas. Nesse caso, uma pergunta n\u00e3o quer se calar: \u201cPor qu\u00ea essa tamanha obedi\u00eancia do deputado ao prefeito?\u201d&#8230; Espalhou-se igual a fogo em palha seca a informa\u00e7\u00e3o de um poss\u00edvel compromisso entre ambos para que o deputado possa ser o candidato de Ney Santos \u00e1 sucess\u00e3o de Fernando Fernandes em Tabo\u00e3o da Serra. No ano passado, em meados de 2018, o prefeito Ney Santos, na euforia da inaugura\u00e7\u00e3o do Comit\u00ea Pol\u00edtico de sua irm\u00e3 Ely Santos como candidata a deputada federal, teria profetizado que iria eleger o presidente da C\u00e2mara e o futuro prefeito de Tabo\u00e3o da Serra. O epis\u00f3dio gerou uma infinidade de polemicas. E, no final de 2018, o prefeito Fernando Fernandes, com a derrota do vereador Ronaldo Onishi a presid\u00eancia da C\u00e2mara, teria percebido que a primeira profecia havia acontecido com a elei\u00e7\u00e3o do vereador Marcos Paulo a presid\u00eancia, com ind\u00edcios de fortes influ\u00eancias de Ney e Apr\u00edgio. Ser\u00e1 que a segunda profecia est\u00e1 em andamento? Se assim for, que futuro aguardam os taboanenses? Ser\u00e1 igual \u00e0 do Embu das Artes, onde o funcionalismo p\u00fablico tem sal\u00e1rios atrasados, onde o povo foi amea\u00e7ado com aumento abusivo do IPTU e a criminosa cria\u00e7\u00e3o da taxa do lixo? Isso sem esquecer das mortes por neglig\u00eancias m\u00e9dicas ocorridas na cidade em 2017 e 2018. Se \u00e9 fato ou boato, ningu\u00e9m sabe ao certo, mas que \u00e9 extremamente tem\u00edvel e perigoso, isto \u00e9.<\/p>\n<p style=\"text-align: center;\">M\u00e1rio Aparecido de Souza<br \/>\nEditor<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta semana, no Canal Folha do Piraju\u00e7ara, eu apresento alguns fatos interessantes e, para n\u00e3o dizer, tamb\u00e9m preocupantes. Trata-se de<\/p>\n","protected":false},"author":3,"featured_media":1793,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,2,4],"tags":[],"class_list":["post-1905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-editorial","category-noticias"],"_links":{"self":[{"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1905"}],"collection":[{"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1905"}],"version-history":[{"count":0,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1905\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/media\/1793"}],"wp:attachment":[{"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}