{"id":2522,"date":"2020-02-25T19:06:24","date_gmt":"2020-02-25T22:06:24","guid":{"rendered":"http:\/\/folhadopirajucara.com.br\/?p=2522"},"modified":"2020-02-25T19:06:24","modified_gmt":"2020-02-25T22:06:24","slug":"rosangela-santos-pre-candidata-a-prefeita-do-pt-de-embu-das-artes","status":"publish","type":"post","link":"https:\/\/folhadopirajucara.com.br\/index.php\/2020\/02\/25\/rosangela-santos-pre-candidata-a-prefeita-do-pt-de-embu-das-artes\/","title":{"rendered":"Ros\u00e2ngela Santos pr\u00e9-candidata a prefeita do PT de Embu das Artes"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2526 alignleft\" src=\"https:\/\/folhadopirajucara.com.br\/wp-content\/uploads\/2020\/02\/rosangela-300x181.jpg\" alt=\"\" width=\"300\" height=\"181\" srcset=\"https:\/\/folhadopirajucara.com.br\/wp-content\/uploads\/2020\/02\/rosangela-300x181.jpg 300w, https:\/\/folhadopirajucara.com.br\/wp-content\/uploads\/2020\/02\/rosangela.jpg 591w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>O Partido dos Trabalhadores oficializou em sua cerim\u00f4nia de posse que ter\u00e1 Ros\u00e2ngela Santos como pr\u00e9-candidata a prefeita em Embu das Artes. O evento, que foi realizado no dia 08 de fevereiro na C\u00e2mara Municipal, serviu para empossar a nova dire\u00e7\u00e3o e presid\u00eancia do partido, contando com a participa\u00e7\u00e3o de mais de 300 pessoas, entre filiados, militantes e simpatizantes.<br \/>\nA vereadora Ros\u00e2ngela Santos foi a figura central do evento, atualmente \u00e9 a l\u00edder de bancada do partido e nos \u00faltimos tr\u00eas anos atuou com muito destaque se tornando a principal lideran\u00e7a do Partido dos Trabalhadores na cidade. E o presidente reeleito, Gabino Silva, declarou oficialmente \u201cnossa pr\u00e9-candidata a prefeita Ros\u00e2ngela Santos\u201d.<br \/>\nEste jornal entrou em contato com o Secret\u00e1rio de Organiza\u00e7\u00e3o empossado, Erismar Santos Silva, que declarou \u201co partido passa por um processo de crescimento e renova\u00e7\u00e3o. Estamos com grandes expectativas por ter algu\u00e9m que teve um papel t\u00e3o importante na cidade nos \u00faltimos anos como a Vereadora Ros\u00e2ngela Santos, que \u00e9 a principal autoridade de oposi\u00e7\u00e3o a este governo e com certeza a \u00fanica capaz de realizar uma mudan\u00e7a na cidade\u201d.<br \/>\nO evento tamb\u00e9m contou com a presen\u00e7a de deputados e presidentes de partidos da cidade, como PSOL, PTC, Cidadania, PCdoB e REDE e presidente dos partidos de cidades vizinhas como Tabo\u00e3o da Serra, Itapecerica da Serra e Cotia, al\u00e9m da coordena\u00e7\u00e3o do PT da macrorregi\u00e3o de Osasco.<br \/>\n\u201cA gente precisa trazer de volta esse orgulho de viver na cidade, com pessoas boas, com pessoas com essa vontade de mudan\u00e7a, com carinho e com empatia, vamos com muita garra e muita energia eleger a primeira mulher prefeita. E tenho certeza de verdade, que n\u00f3s vamos fazer a melhor gest\u00e3o que Embu das Artes j\u00e1 teve!\u201d afirmou Ros\u00e2ngela em seu discurso.<\/p>\n<p><strong>Papel de Ros\u00e2ngela Santos na cidade<\/strong><\/p>\n<p>Ros\u00e2ngela, que tem origem nos movimentos sociais, tendo sido a vereadora mais votada da cidade nas elei\u00e7\u00f5es de 2016, ganhou notoriedade na cidade ao ser a \u00fanica vereadora a se posicionar desde o in\u00edcio contra a taxa do lixo.<br \/>\nAp\u00f3s a luta contra a taxa do lixo, Ros\u00e2ngela continuou atuando como a principal figura de oposi\u00e7\u00e3o da cidade, realizando batalhas contra o aumento do IPTU (que havia sido calculado incorretamente com aumentos astron\u00f4micos), posicionou-se contra o corte salarial dos professores municipais (PDIs) e reivindicando que a verba p\u00fablica seja utilizada de forma consciente, evitando o atraso dos sal\u00e1rios dos servidores municipais, desde a ala administrativa at\u00e9 os m\u00e9dicos que estavam sem receber. Al\u00e9m disso, apresentou mais de 30 projetos que repercutiram pela cidade, um exemplo \u00e9 o Bilhete \u00danico Municipal que prev\u00ea a integra\u00e7\u00e3o entre os \u00f4nibus da cidade.<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2525 alignleft\" src=\"https:\/\/folhadopirajucara.com.br\/wp-content\/uploads\/2020\/02\/rosangela-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/folhadopirajucara.com.br\/wp-content\/uploads\/2020\/02\/rosangela-1-300x200.jpg 300w, https:\/\/folhadopirajucara.com.br\/wp-content\/uploads\/2020\/02\/rosangela-1.jpg 591w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>A nova executiva do PT \u00e9 composta por:<\/strong><\/p>\n<p>Abaldino (Gabino) Ferreira da Silva \u2013 Presidente<br \/>\nErismar dos Santos Silva \u2013 Secretaria de Organiza\u00e7\u00e3o<br \/>\nEveraldo Batista Neves \u2013 Vice-presidente<br \/>\nAngelo Archibald Grenfell \u2013 Secretaria de Finan\u00e7as e Planejamento<br \/>\nDaniele Tatiane Marin \u2013 Secretaria de Movimentos Populares<br \/>\nElba Marcia de Santana Santos \u2013 Secretaria de Forma\u00e7\u00e3o Pol\u00edtica<br \/>\nJosiane dos Santos Oliveira \u2013 Secretaria de Comunica\u00e7\u00e3o<br \/>\nRos\u00e2ngela Silva dos Santos (vereadora) \u2013 L\u00edder da bancada<\/p>\n<p>Compuseram a mesa do evento as pessoas:<\/p>\n<p>Lu\u00edza Rodrigues &#8211; representando o Deputado Federal Alencar Santana;<br \/>\nRoberta Luchsinger \u2013 PT S\u00e3o Paulo (capital);<br \/>\nValdir Roque &#8211; Coordenador do PT Macro Osasco e regi\u00e3o;<br \/>\nH\u00e9lio Rodrigues &#8211; Coordenador do sindicato dos Qu\u00edmicos S\u00e3o Paulo e Regi\u00e3o;<br \/>\nJorge do Carmo &#8211; Deputado Estadual do PT;<br \/>\nMauricio Louren\u00e7o &#8211; presidente do PT Tabo\u00e3o da Serra;<br \/>\nPaulo Flamingo &#8211; presidente do PT Itapecerica da Serra;<br \/>\nBosco, presidente do PT Bom Jesus de Pirapora;<br \/>\nCarlito Oliveira &#8211; presidente do PT Campo Limpo \u2013 SP;<br \/>\nEdson Bertoldo &#8211; diretor do Sindicato dos Empregados no Com\u00e9rcio Osasco e regi\u00e3o;<br \/>\nDaniel Reis &#8211; Sindicato dos Banc\u00e1rios S\u00e3o Paulo, Osasco e Regi\u00e3o;<br \/>\nSilvio Vital &#8211; Secret\u00e1rio de Assuntos Institucionais do PT Estadual;<br \/>\nBatista &#8211; presidente do Sindicato dos Motoristas de Transporte de cargas;<br \/>\nSandro &#8211; presidente do PC do B Embu das Artes;<br \/>\nRobson Oliveira &#8211; coordenador do REDE Embu das Artes;<br \/>\nMarcelo Rodrigues &#8211; presidente do PTC Embu das Artes;<br \/>\nProfessor Toninho &#8211; Presidente do PSOL Embu das Artes;<br \/>\nJo\u00e3o Caetano da Paix\u00e3o &#8211; Presidente do CIDADANIA Embu das Artes.<br \/>\nAl\u00e9m disso, foram enviadas sauda\u00e7\u00f5es em v\u00eddeos dos deputados Beth Sahao, Luiz Fernando e a vereadora Juliana Cardoso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Partido dos Trabalhadores oficializou em sua cerim\u00f4nia de posse que ter\u00e1 Ros\u00e2ngela Santos como pr\u00e9-candidata a prefeita em Embu<\/p>\n","protected":false},"author":3,"featured_media":2523,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,15,4],"tags":[],"class_list":["post-2522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-embu-das-artes","category-noticias"],"_links":{"self":[{"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2522"}],"collection":[{"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2522"}],"version-history":[{"count":0,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2522\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/media\/2523"}],"wp:attachment":[{"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}