{"id":5512,"date":"2022-08-15T14:46:31","date_gmt":"2022-08-15T17:46:31","guid":{"rendered":"http:\/\/folhadopirajucara.com.br\/?p=5512"},"modified":"2022-08-15T14:46:31","modified_gmt":"2022-08-15T17:46:31","slug":"feira-de-empregos-do-grau-taboao-realizou-mais-de-130-processos-seletivos","status":"publish","type":"post","link":"https:\/\/folhadopirajucara.com.br\/index.php\/2022\/08\/15\/feira-de-empregos-do-grau-taboao-realizou-mais-de-130-processos-seletivos\/","title":{"rendered":"Feira de Empregos do Grau Tabo\u00e3o realizou mais de 130 processos seletivos"},"content":{"rendered":"<div>A\u00a0I Feira de Empregabilidade Grau T\u00e9cnico Tabo\u00e3o\u00a0encaminhou mais de 130 pessoas para os processos de sele\u00e7\u00e3o, dispon\u00edveis durante todo o dia. Centenas de vagas de emprego e est\u00e1gio, em diversas \u00e1reas, foram oferecidas, al\u00e9m de servi\u00e7os das empresas e organiza\u00e7\u00f5es parceiras.<\/div>\n<p>O evento aconteceu no \u00faltimo dia 28 de julho e foi totalmente gratuito \u00e0 popula\u00e7\u00e3o.<\/p>\n<p>\u201cFoi uma experi\u00eancia maravilhosa, conhecemos muitas pessoas e pudemos mostrar um pouco do nosso trabalho na fisioterapia\u201d, disse Elaine Soares da Clinic Corpore, ela \u00e9 fisioterapeuta e j\u00e1 garantiu que a empresa quer estar presente na pr\u00f3xima edi\u00e7\u00e3o.<\/p>\n<p>Participaram empresas como o CIEE, Nube, Sercom, Espa\u00e7o Viva Bem, Odonto Company, GiOlaser, Salus Enfermagem, Sorria, Clinic Corpore, Master Healt, Master Med, Wizard, Teleperformance, EmpreVitae, Supera, System e Sebrae.<\/p>\n<p>\u201cEssa feira foi preparada e pensada para toda a popula\u00e7\u00e3o de Tabo\u00e3o e regi\u00e3o! Nossos jovens estudantes, e mesmo profissionais formados devem sempre valorizar essas oportunidades. Tudo o que queremos \u00e9 oferecer as ferramentas necess\u00e1rias para a conquista do t\u00e3o sonhado emprego\u201d, afirma o diretor do Grau Tabo\u00e3o da Serra, Gleyvson Ferreira.<\/p>\n<p>No evento tamb\u00e9m foi poss\u00edvel realizar testes de glicose (Diabetes), aferi\u00e7\u00e3o da press\u00e3o (Hipertens\u00e3o), palestras e os processos seletivos. \u201cFoi uma experi\u00eancia muito boa, recebemos o curr\u00edculo de v\u00e1rios candidatos e encaminhamos v\u00e1rios deles para os processos seletivos\u201d, informou a analista de recrutamento e sele\u00e7\u00e3o a empresa Teleperformance, Isabela, designada para o evento.<\/p>\n<p>Beatris Silva, de 19 anos, \u00e9 a respons\u00e1vel pela Ag\u00eancia de Empregos do Grau T\u00e9cnico, ela comentou sobre sua participa\u00e7\u00e3o. \u201cAs expectativas estavam bem grandes para esse dia, atuo na \u00e1rea de RH trabalhando diretamente com pessoas h\u00e1 anos, jamais havia participado e organizado um evento como este, a primeira feira de empregabilidade foi al\u00e9m das nossas expectativas e tenho certeza que tamb\u00e9m foi para quem participou, ver que as pessoas puderam se recolar no mercado de trabalho, tiveram a oportunidade de conhecer mais sobre os empreendedores da regi\u00e3o \u00e9 algo incr\u00edvel\u201d disse ela.<\/p>\n<p>\u201cConsidero que essa feira foi s\u00f3 o in\u00edcio de muitos outros projetos que n\u00f3s do Grau T\u00e9cnico Tabo\u00e3o da Serra pensamos em realizar\u201d.<\/p>\n<p>A escola em Tabo\u00e3o, oferece cursos nas \u00e1reas de Enfermagem, Eletrot\u00e9cnica, Administra\u00e7\u00e3o e Radiologia. Est\u00e1 localizada na Av. Caetano Barrela, 89 (Rua do Cart\u00f3rio). O telefone para mais informa\u00e7\u00f5es \u00e9: 11 4786-0096.<\/p>\n<p>&nbsp;<\/p>\n<p>*por: Marcelo Vallad\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A\u00a0I Feira de Empregabilidade Grau T\u00e9cnico Tabo\u00e3o\u00a0encaminhou mais de 130 pessoas para os processos de sele\u00e7\u00e3o, dispon\u00edveis durante todo o<\/p>\n","protected":false},"author":3,"featured_media":5513,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,4,10],"tags":[],"class_list":["post-5512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-noticias","category-taboao-da-serra"],"_links":{"self":[{"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5512"}],"collection":[{"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5512"}],"version-history":[{"count":1,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5512\/revisions"}],"predecessor-version":[{"id":5514,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5512\/revisions\/5514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/media\/5513"}],"wp:attachment":[{"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}