{"id":8689,"date":"2025-01-22T13:54:18","date_gmt":"2025-01-22T16:54:18","guid":{"rendered":"https:\/\/folhadopirajucara.com.br\/?p=8689"},"modified":"2025-01-23T14:06:28","modified_gmt":"2025-01-23T17:06:28","slug":"rose-dorea-agitadora-cultural-morre-em-sao-paulo-aos-51-anos","status":"publish","type":"post","link":"https:\/\/folhadopirajucara.com.br\/index.php\/2025\/01\/22\/rose-dorea-agitadora-cultural-morre-em-sao-paulo-aos-51-anos\/","title":{"rendered":"Rose Dorea, agitadora cultural, morre em S\u00e3o Paulo aos 51 anos"},"content":{"rendered":"<div class=\"td_block_wrap tdb_single_content tdi_61 td-pb-border-top td_block_template_1 td-post-content tagdiv-type\" data-td-block-uid=\"tdi_61\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>Rose Dorea, importante agitadora cultural de Tabo\u00e3o da Serra, faleceu aos 51 anos em S\u00e3o Paulo, na noite de ter\u00e7a-feira, 21. Ela estava internada no Hospital do Campo Limpo ap\u00f3s sofrer um acidente vascular cerebral (AVC) e ser diagnosticada com um tumor no c\u00e9rebro. Sua morte causou grande como\u00e7\u00e3o, especialmente entre artistas e ativistas culturais da regi\u00e3o.<\/p>\n<p>Rose foi uma figura marcante na cena cultural, tendo contribu\u00eddo significativamente para o fortalecimento da arte e da literatura em Tabo\u00e3o da Serra. Ela esteve fortemente ligada ao Sarau da Cooperifa, um dos mais importantes movimentos culturais e liter\u00e1rios da periferia de S\u00e3o Paulo, lugar onde desempenhou um papel ativo na dissemina\u00e7\u00e3o de cultura e no incentivo \u00e0 express\u00e3o art\u00edstica.<\/p>\n<p>Al\u00e9m de sua atua\u00e7\u00e3o no sarau, Rose organizou e participou de diversos eventos culturais ao longo de sua trajet\u00f3ria, sempre com foco na valoriza\u00e7\u00e3o das vozes perif\u00e9ricas e na inclus\u00e3o social atrav\u00e9s da arte. Sua energia e entusiasmo a tornaram uma refer\u00eancia para muitos que buscavam inspira\u00e7\u00e3o para transformar suas realidades por meio da cultura.<\/p>\n<p>Amigos e colegas prestaram homenagens emocionadas, destacando sua dedica\u00e7\u00e3o incans\u00e1vel e o impacto de seu trabalho na comunidade, como o poeta S\u00e9rgio Vaz. \u201cA Rose Dorea, nossa irm\u00e3 e eterna musa da Cooperifa acaba de nos deixar. A not\u00edcia \u00e9 t\u00e3o devastadora que n\u00e3o h\u00e1 palavras para descrever o que estamos sentindo. \u00c9 s\u00f3 dor e l\u00e1grimas\u201d, disse.<\/p>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>*por: Dereck Gomes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rose Dorea, importante agitadora cultural de Tabo\u00e3o da Serra, faleceu aos 51 anos em S\u00e3o Paulo, na noite de ter\u00e7a-feira,<\/p>\n","protected":false},"author":3,"featured_media":8690,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,4,10],"tags":[],"class_list":["post-8689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-noticias","category-taboao-da-serra"],"_links":{"self":[{"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8689"}],"collection":[{"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=8689"}],"version-history":[{"count":1,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8689\/revisions"}],"predecessor-version":[{"id":8691,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8689\/revisions\/8691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/media\/8690"}],"wp:attachment":[{"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=8689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=8689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadopirajucara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=8689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}